{"id":1152,"date":"2017-10-17T10:55:41","date_gmt":"2017-10-17T08:55:41","guid":{"rendered":"https:\/\/fastforwardscience.de\/vernetztes-leben"},"modified":"2019-02-05T17:20:17","modified_gmt":"2019-02-05T16:20:17","slug":"vernetztes-leben","status":"publish","type":"post","link":"https:\/\/fastforwardscience.de\/en\/2017\/10\/vernetztes-leben\/","title":{"rendered":"Vernetztes Leben"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<?xml encoding=\"utf-8\" ?><html><body><p>&bdquo;Dr. Dr. Dr. Dr. Dr. Luca&ldquo; pr&auml;sentiert unser heutiges Finalisten-Video und es geht um: Fische! Dahinter steckt allerdings viel mehr, denn im Meer sind alle Lebewesen miteinander vernetzt.<\/p>\n<p>So funktioniert der Meeres-Kreislauf: Fische fressen kleinere Wassertiere und scheiden danach mit ihren Exkrementen auch N&auml;hrstoffe aus. Diese sind zum Beispiel f&uuml;r Pflanzen im und am Wasser wichtig. Doch auch Plankton ben&ouml;tigt diese N&auml;hrstoffe, um zu wachsen und sich zu vermehren. Und f&uuml;r die anderen Lebewesen im Wasser dient Plankton wiederum als Nahrung. Es wird zum Beispiel von kleinen Krebsen aufgenommen. Und nun sind wieder die Fische an der Reihe: Sie fressen die Krebse und &hellip; ihr wisst schon!<\/p>\n<p>Dass der kleine Luca das Zeug zu einem gro&szlig;artigen Wissenschaftler hat, beweist er in diesem liebensw&uuml;rdigen Video, was am AWO B&uuml;rgerzentrum der <a href=\"https:\/\/www.projektraeucherei.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">R&auml;ucherei Kiel <\/a>entstanden ist. &bdquo;Vernetzt&ldquo; war &uuml;brigens Thema unserer Super Fast Challenge, bei der dieses Video den 3. Platz belegt hat.<\/p>\n<p><a href=\"http:\/\/www.fastforwardscience.de\/gewinnspiel.html\">Gewinnspielfrage<\/a>: Von welchem N&auml;hrstoff ist hier die Rede?<\/p>\n<p><iframe loading=\"lazy\" src=\"\" width=\"550\" height=\"309\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-blocked-src=\"https:\/\/www.youtube-nocookie.com\/embed\/QsTHhAq6s2M?list=PLlK_JXw2dOnMox7olM51MGbJzfCst92kU\" data-copy-size=\"true\"><\/iframe><\/p>\n<p><strong>#VoteNow &ndash; so funktioniert&rsquo;s:<\/strong><\/p>\n<p>Euch gef&auml;llt das Video? Dann kommentiert und likt es auf YouTube! Denn &bdquo;Vernetztes Leben&ldquo; geh&ouml;rt zu den 21 Finalisten von Fast Forward Science 2017, die vom 4. bis 31. Oktober am Online-Voting teilnehmen. Das hei&szlig;t: Ihr entscheidet, welche Videos einen der drei <a href=\"http:\/\/www.fastforwardscience.de\/kategorien-und-preise\/community-award.html\">Community Awards<\/a> gewinnen. Wie? Ganz einfach: Es z&auml;hlen eure Likes und Kommentare auf YouTube. Viel Spa&szlig; beim Voten! Und wenn ihr uns au&szlig;erdem noch die richtige Antwort auf eine unserer Gewinnspielfragen schickt (an: <a href=\"mailto:onlinevoting-ffs@w-i-d.de\">onlinevoting-ffs@w-i-d.de<\/a>), habt ihr die Chance, eine von zwei VR One Plus Brillen unseres Sponsors ZEISS oder ein GEO-Jahresabo zu gewinnen.&nbsp;<a href=\"http:\/\/www.fastforwardscience.de\/gewinnspiel.html\">Zum Gewinnspiel.&nbsp;<\/a><\/p>\n<p>Hier findet ihr alle&nbsp;<a href=\"https:\/\/www.youtube.com\/playlist?list=PLlK_JXw2dOnMox7olM51MGbJzfCst92kU\">Finalisten<\/a>&nbsp;im &Uuml;berblick.<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"<p>&bdquo;Dr. Dr. Dr. Dr. Dr. Luca&ldquo; pr&auml;sentiert unser heutiges Finalisten-Video und es geht um: Fische! Dahinter steckt allerdings viel mehr, denn im Meer sind alle Lebewesen miteinander vernetzt. So funktioniert der Meeres-Kreislauf: Fische fressen kleinere Wassertiere und scheiden danach mit ihren Exkrementen auch N&auml;hrstoffe aus. Diese sind zum Beispiel f&uuml;r Pflanzen im und am Wasser [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2132,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3,4],"tags":[16,17,77,209,341],"class_list":["post-1152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-superfast","category-votenow","tag-superfast","tag-votenow","tag-community-award","tag-meeresforschung","tag-vernetzt"],"acf":{"post_video":"","file_webm":false,"file_mp4":false},"_links":{"self":[{"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/posts\/1152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/comments?post=1152"}],"version-history":[{"count":3,"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/posts\/1152\/revisions"}],"predecessor-version":[{"id":3418,"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/posts\/1152\/revisions\/3418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/media\/2132"}],"wp:attachment":[{"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/media?parent=1152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/categories?post=1152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/tags?post=1152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}