{"id":1104,"date":"2017-10-05T11:26:24","date_gmt":"2017-10-05T09:26:24","guid":{"rendered":"https:\/\/fastforwardscience.de\/der-tod-des-internets"},"modified":"2019-02-05T11:29:47","modified_gmt":"2019-02-05T10:29:47","slug":"der-tod-des-internets","status":"publish","type":"post","link":"https:\/\/fastforwardscience.de\/en\/2017\/10\/der-tod-des-internets\/","title":{"rendered":"Der Tod des Internets"},"content":{"rendered":"<!DOCTYPE html PUBLIC \"-\/\/W3C\/\/DTD HTML 4.0 Transitional\/\/EN\" \"http:\/\/www.w3.org\/TR\/REC-html40\/loose.dtd\">\n<?xml encoding=\"utf-8\" ?><html><body><p>&bdquo;Es konnte keine Verbindung zum Internet hergestellt werden.&ldquo; Wer kennt das nicht? Da m&ouml;chte man sich gem&uuml;tlich durch YouTube klicken und dann so etwas. Kurz den Router neugestartet und meist ist das Problem schon behoben. Doch was, wenn das Internet einmal wirklich ausf&auml;llt? Nicht f&uuml;r eine Stunde, nicht f&uuml;r einen Tag, sondern f&uuml;r immer? Gar nicht so unwahrscheinlich, wie Lars Fischer und Mike Beckers vom Wissenschafts-Videocast <a href=\"https:\/\/www.youtube.com\/channel\/UCLFD23LAjhxKnwLlyCErqWA\">Wir werden alle sterben<\/a> erkl&auml;ren.<\/p>\n<p>Das Internet verbindet uns &ndash; wortw&ouml;rtlich. Es ist ein riesiges Netzwerk, das sich aus verschiedensten Komponenten wie Leitungen und Servern zusammensetzt und &uuml;ber den ganzen Planeten erstreckt. Einmal aufgebaut, muss es allerdings st&auml;ndig kontrolliert und gewartet werden, denn die Technik lebt leider nicht ewig. Neue Bauteile wollen also produziert und eingebaut werden, was nat&uuml;rlich dementsprechend aufw&auml;ndig und teuer ist. Sehr anschaulich wird im Video beschrieben, wie anf&auml;llig diese Struktur ist und was alles dazu f&uuml;hren k&ouml;nnte, dass wir eines Tages offline sind. Aber das wollen wir nat&uuml;rlich nicht hoffen!<\/p>\n<p>Besonders beeindruckend: Dieser Beitrag ist im Rahmen von <a href=\"http:\/\/www.fastforwardscience.de\/kategorien-und-preise\/super-fast.html\">Super Fast<\/a> unter dem Thema &bdquo;VERNETZT&ldquo; entstanden, also innerhalb von nur zwei Tagen!<\/p>\n<p><a href=\"http:\/\/www.fastforwardscience.de\/gewinnspiel.html\">Gewinnspielfrage<\/a><strong>:<\/strong> Welche durchschnittliche Lebensdauer hat ein Rechner?<\/p>\n<p><iframe loading=\"lazy\" src=\"\" width=\"550\" height=\"309\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-blocked-src=\"https:\/\/www.youtube-nocookie.com\/embed\/ga4F9s-AdH8?rel=0\" data-copy-size=\"true\"><\/iframe><\/p>\n<p><strong> #VoteNow &ndash; so funktioniert&rsquo;s:<\/strong><\/p>\n<p>Euch gef&auml;llt das Video? Dann kommentiert und likt es auf YouTube! Denn &bdquo;Der Tod des Internets&ldquo; geh&ouml;rt zu den 21&nbsp;Finalisten von Fast Forward Science 2017, die vom 4. bis 31. Oktober am Online-Voting teilnehmen. Das hei&szlig;t: Ihr entscheidet, welche Videos einen der drei <a href=\"http:\/\/www.fastforwardscience.de\/kategorien-und-preise\/community-award.html\">Community Awards<\/a> gewinnen. Wie? Ganz einfach: Es z&auml;hlen eure Likes und Kommentare auf YouTube. Viel Spa&szlig; beim Voten! Und wenn ihr uns au&szlig;erdem noch die richtige Antwort auf eine unserer Gewinnspielfragen schickt (an: <a href=\"mailto:onlinevoting-ffs@w-i-d.de\">onlinevoting-ffs@w-i-d.de<\/a>), habt ihr die Chance, eine von zwei VR One Plus Brillen unseres Sponsors ZEISS oder ein GEO-Jahresabo zu gewinnen.&nbsp;<a href=\"http:\/\/www.fastforwardscience.de\/gewinnspiel.html\">Zum Gewinnspiel<\/a>.<\/p>\n<p>Hier findet ihr alle<strong>&nbsp;<\/strong><a href=\"https:\/\/www.youtube.com\/watch?v=ga4F9s-AdH8&amp;index=1&amp;list=PLlK_JXw2dOnMox7olM51MGbJzfCst92kU\">Finalisten<\/a><strong>&nbsp;<\/strong>im &Uuml;berblick.<\/p>\n<\/body><\/html>\n","protected":false},"excerpt":{"rendered":"<p>&bdquo;Es konnte keine Verbindung zum Internet hergestellt werden.&ldquo; Wer kennt das nicht? Da m&ouml;chte man sich gem&uuml;tlich durch YouTube klicken und dann so etwas. Kurz den Router neugestartet und meist ist das Problem schon behoben. Doch was, wenn das Internet einmal wirklich ausf&auml;llt? Nicht f&uuml;r eine Stunde, nicht f&uuml;r einen Tag, sondern f&uuml;r immer? Gar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4],"tags":[16,17,77,194,307,368],"class_list":["post-1104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-votenow","tag-superfast","tag-votenow","tag-community-award","tag-lars-fischer","tag-super-fast","tag-wir-werden-alle-sterben"],"acf":{"post_video":"","file_webm":false,"file_mp4":false},"_links":{"self":[{"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/posts\/1104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/comments?post=1104"}],"version-history":[{"count":3,"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/posts\/1104\/revisions"}],"predecessor-version":[{"id":3229,"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/posts\/1104\/revisions\/3229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/media\/2137"}],"wp:attachment":[{"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/media?parent=1104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/categories?post=1104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fastforwardscience.de\/en\/wp-json\/wp\/v2\/tags?post=1104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}